{"id":20412,"date":"2022-10-14T17:37:27","date_gmt":"2022-10-14T15:37:27","guid":{"rendered":"http:\/\/www.oliosanfilippo.com\/?page_id=20412"},"modified":"2024-10-30T22:48:35","modified_gmt":"2024-10-30T21:48:35","slug":"olio-extravergine-di-oliva","status":"publish","type":"page","link":"https:\/\/www.oliosanfilippo.com\/de\/olio-extravergine-di-oliva\/","title":{"rendered":"Natives Oliven\u00f6l extra"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"20412\" class=\"elementor elementor-20412\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-83746e8 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"83746e8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-09faee3\" data-id=\"09faee3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-f3a46e2 elementor-section-height-min-height elementor-section-full_width elementor-section-height-default\" data-id=\"f3a46e2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e40b6e3\" data-id=\"e40b6e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-384fbd1 elementor-widget elementor-widget-image\" data-id=\"384fbd1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"887\" src=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2022\/10\/oliotaste-1024x887.jpg\" class=\"attachment-large size-large wp-image-20457\" alt=\"\" srcset=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2022\/10\/oliotaste-1024x887.jpg 1024w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2022\/10\/oliotaste-300x260.jpg 300w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2022\/10\/oliotaste-768x665.jpg 768w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2022\/10\/oliotaste-1536x1330.jpg 1536w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2022\/10\/oliotaste-900x779.jpg 900w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2022\/10\/oliotaste-600x520.jpg 600w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2022\/10\/oliotaste.jpg 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b2f88d4\" data-id=\"b2f88d4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b7e8954 elementor-widget elementor-widget-image\" data-id=\"b7e8954\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2018\/01\/cropped-logo-icona-1-6.png\" class=\"attachment-large size-large wp-image-11710\" alt=\"\" srcset=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2018\/01\/cropped-logo-icona-1-6.png 512w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2018\/01\/cropped-logo-icona-1-6-150x150.png 150w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2018\/01\/cropped-logo-icona-1-6-300x300.png 300w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2018\/01\/cropped-logo-icona-1-6-200x200.png 200w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2018\/01\/cropped-logo-icona-1-6-500x500.png 500w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2018\/01\/cropped-logo-icona-1-6-270x270.png 270w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2018\/01\/cropped-logo-icona-1-6-192x192.png 192w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2018\/01\/cropped-logo-icona-1-6-180x180.png 180w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2018\/01\/cropped-logo-icona-1-6-32x32.png 32w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45b7226 elementor-widget elementor-widget-text-editor\" data-id=\"45b7226\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Produkte unserer jahrhundertealten Traditionen<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7152a9 elementor-widget elementor-widget-heading\" data-id=\"c7152a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Entdecken Sie unser unglaubliches Natives Oliven\u00f6l Extra<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fee1a1 elementor-widget elementor-widget-text-editor\" data-id=\"4fee1a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>ausschlie\u00dflich aus italienischen Bergoliven 100% gewonnen<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-6f3b648 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f3b648\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eaca9a1\" data-id=\"eaca9a1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fb860d elementor-widget elementor-widget-heading\" data-id=\"5fb860d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unsere feinen abgef\u00fcllten \u00d6le<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd52498 elementor-grid-mobile-1 elementor-grid-4 elementor-grid-tablet-3 elementor-products-grid elementor-wc-products elementor-widget elementor-widget-woocommerce-products\" data-id=\"dd52498\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"woocommerce-products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"woocommerce columns-4\"><ul class=\"products elementor-grid content-wrap product-archive grid-cols grid-ss-col-2 grid-sm-col-3 grid-lg-col-4 woo-archive-action-visible woo-archive-btn-text align-buttons-bottom  woo-archive-image-hover-zoom\"><li class=\"entry content-bg loop-entry product type-product post-22994 status-publish first instock product_cat-olio-extravergine-di-oliva product_tag-fruttato-delicato product_tag-fruttato-medio product_tag-olio-extravergine-di-oliva product_tag-olio-in-bottiglia has-post-thumbnail shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/www.oliosanfilippo.com\/de\/abbonamento\/olio-extravergine-di-oliva-novello\/\" class=\"woocommerce-loop-image-link woocommerce-LoopProduct-link woocommerce-loop-product__link product-has-hover-image\"><img decoding=\"async\" width=\"900\" height=\"1204\" src=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2024\/10\/Alikos-900x1204.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Alik\u00f2s Olio EVO Novello Fresco di Frantoio 2025\" srcset=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2024\/10\/Alikos-900x1204.png 900w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2024\/10\/Alikos-224x300.png 224w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2024\/10\/Alikos-765x1024.png 765w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2024\/10\/Alikos-768x1028.png 768w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2024\/10\/Alikos-1148x1536.png 1148w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2024\/10\/Alikos-1530x2048.png 1530w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2024\/10\/Alikos-9x12.png 9w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2024\/10\/Alikos-600x803.png 600w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2024\/10\/Alikos.png 1913w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/10\/olio-900x506.png\" class=\"secondary-product-image attachment-woocommerce_thumbnail attachment-shop-catalog wp-post-image wp-post-image--secondary\" alt=\"\" title=\"olio\" srcset=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/10\/olio-900x506.png 900w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/10\/olio-300x169.png 300w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/10\/olio-1024x576.png 1024w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/10\/olio-768x432.png 768w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/10\/olio-18x10.png 18w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/10\/olio-600x338.png 600w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/10\/olio.png 1200w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><div class=\"product-details content-bg entry-content-wrap\"><h2 class=\"woocommerce-loop-product__title\"><a href=\"https:\/\/www.oliosanfilippo.com\/de\/abbonamento\/olio-extravergine-di-oliva-novello\/\" class=\"woocommerce-LoopProduct-link-title woocommerce-loop-product__title_ink\">Alik\u00f2s Olio EVO Novello Fresco di Frantoio 2025<\/a><\/h2>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">\u20ac<\/span>20.00<\/bdi><\/span><\/span>\n<div class=\"product-action-wrap\"><a href=\"\/de\/wp-json\/wp\/v2\/pages\/20412?add-to-cart=22994\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"22994\" data-product_sku=\"Novello Fresco di stagione\" aria-label=\"In den Warenkorb legen: &quot;Alik\u00f2s Olio EVO Novello Fresco di Frantoio 2025&quot;\" rel=\"nofollow\" data-success_message=\"\u201eAlik\u00f2s Olio EVO Novello Fresco di Frantoio 2025\u201c wurde deinem Warenkorb hinzugef\u00fcgt\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\">In den Warenkorb<span class=\"kadence-svg-iconset svg-baseline\"><svg aria-hidden=\"true\" class=\"kadence-svg-icon kadence-arrow-right-alt-svg\" fill=\"currentColor\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"28\" viewbox=\"0 0 27 28\"><title>Fortfahren<\/title><path d=\"M27 13.953c0 0.141-0.063 0.281-0.156 0.375l-6 5.531c-0.156 0.141-0.359 0.172-0.547 0.094-0.172-0.078-0.297-0.25-0.297-0.453v-3.5h-19.5c-0.281 0-0.5-0.219-0.5-0.5v-3c0-0.281 0.219-0.5 0.5-0.5h19.5v-3.5c0-0.203 0.109-0.375 0.297-0.453s0.391-0.047 0.547 0.078l6 5.469c0.094 0.094 0.156 0.219 0.156 0.359v0z\"><\/path>\n\t\t\t\t<\/svg><\/span><span class=\"kadence-svg-iconset svg-baseline\"><svg class=\"kadence-svg-icon kadence-spinner-svg\" fill=\"currentColor\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewbox=\"0 0 16 16\"><title>Wird geladen<\/title><path d=\"M16 6h-6l2.243-2.243c-1.133-1.133-2.64-1.757-4.243-1.757s-3.109 0.624-4.243 1.757c-1.133 1.133-1.757 2.64-1.757 4.243s0.624 3.109 1.757 4.243c1.133 1.133 2.64 1.757 4.243 1.757s3.109-0.624 4.243-1.757c0.095-0.095 0.185-0.192 0.273-0.292l1.505 1.317c-1.466 1.674-3.62 2.732-6.020 2.732-4.418 0-8-3.582-8-8s3.582-8 8-8c2.209 0 4.209 0.896 5.656 2.344l2.343-2.344v6z\"><\/path>\n\t\t\t\t<\/svg><\/span><span class=\"kadence-svg-iconset svg-baseline\"><svg class=\"kadence-svg-icon kadence-check-svg\" fill=\"currentColor\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewbox=\"0 0 16 16\"><title>Erledigt<\/title><path d=\"M14 2.5l-8.5 8.5-3.5-3.5-1.5 1.5 5 5 10-10z\"><\/path>\n\t\t\t\t<\/svg><\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_22994\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div><\/div><\/li>\n<li class=\"entry content-bg loop-entry product type-product post-22547 status-publish instock product_cat-olio-extravergine-di-oliva product_tag-fruttato-delicato product_tag-fruttato-medio product_tag-olio-extravergine-di-oliva product_tag-olio-in-bottiglia has-post-thumbnail sale shipping-taxable purchasable product-type-variable\">\n\t<a href=\"https:\/\/www.oliosanfilippo.com\/de\/abbonamento\/olio-extravergine-di-oliva-biologico-bottiglia\/\" class=\"woocommerce-loop-image-link woocommerce-LoopProduct-link woocommerce-loop-product__link product-has-hover-image\">\n\t<span class=\"onsale\" data-no-translation=\"\" data-trp-gettext=\"\">Angebot!<\/span>\n\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"1204\" src=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/okbiologico-scaled-900x1204.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Olio Extravergine di Oliva Biologico - Bottiglia\" srcset=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/okbiologico-scaled-900x1204.jpg 900w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/okbiologico-scaled-600x803.jpg 600w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/okbiologico-224x300.jpg 224w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/okbiologico-765x1024.jpg 765w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/okbiologico-768x1028.jpg 768w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/okbiologico-1148x1536.jpg 1148w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/okbiologico-1530x2048.jpg 1530w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/okbiologico-scaled.jpg 1913w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Olio-extravergine-di-oliva-biologico-0-50-.jpg\" class=\"secondary-product-image attachment-woocommerce_thumbnail attachment-shop-catalog wp-post-image wp-post-image--secondary\" alt=\"\" title=\"Natives Oliven\u00f6l extra - biologisch - 0-50 -.jpg\" srcset=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Olio-extravergine-di-oliva-biologico-0-50-.jpg 800w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Olio-extravergine-di-oliva-biologico-0-50--300x300.jpg 300w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Olio-extravergine-di-oliva-biologico-0-50--150x150.jpg 150w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Olio-extravergine-di-oliva-biologico-0-50--768x768.jpg 768w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Olio-extravergine-di-oliva-biologico-0-50--600x600.jpg 600w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Olio-extravergine-di-oliva-biologico-0-50--100x100.jpg 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><div class=\"product-details content-bg entry-content-wrap\"><h2 class=\"woocommerce-loop-product__title\"><a href=\"https:\/\/www.oliosanfilippo.com\/de\/abbonamento\/olio-extravergine-di-oliva-biologico-bottiglia\/\" class=\"woocommerce-LoopProduct-link-title woocommerce-loop-product__title_ink\">Natives Bio-Oliven\u00f6l Extra - Flasche<\/a><\/h2>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>11.00<\/bdi><\/span> <span aria-hidden=\"true\"> \u2013 <\/span> <span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>125.00<\/bdi><\/span><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Preisspanne: &euro;11.00 bis &euro;125.00<\/span><\/span>\n<div class=\"product-action-wrap\"><a href=\"https:\/\/www.oliosanfilippo.com\/de\/abbonamento\/olio-extravergine-di-oliva-biologico-bottiglia\/\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"22547\" data-product_sku=\"Biologico Bottiglia\" aria-label=\"W\u00e4hle Optionen f\u00fcr \u201eOlio Extravergine di Oliva Biologico - Bottiglia\u201c\" rel=\"nofollow\" data-no-translation-aria-label=\"\">Ausf\u00fchrung w\u00e4hlen<span class=\"kadence-svg-iconset svg-baseline\"><svg aria-hidden=\"true\" class=\"kadence-svg-icon kadence-arrow-right-alt-svg\" fill=\"currentColor\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"28\" viewbox=\"0 0 27 28\"><title>Fortfahren<\/title><path d=\"M27 13.953c0 0.141-0.063 0.281-0.156 0.375l-6 5.531c-0.156 0.141-0.359 0.172-0.547 0.094-0.172-0.078-0.297-0.25-0.297-0.453v-3.5h-19.5c-0.281 0-0.5-0.219-0.5-0.5v-3c0-0.281 0.219-0.5 0.5-0.5h19.5v-3.5c0-0.203 0.109-0.375 0.297-0.453s0.391-0.047 0.547 0.078l6 5.469c0.094 0.094 0.156 0.219 0.156 0.359v0z\"><\/path>\n\t\t\t\t<\/svg><\/span><span class=\"kadence-svg-iconset svg-baseline\"><svg class=\"kadence-svg-icon kadence-spinner-svg\" fill=\"currentColor\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewbox=\"0 0 16 16\"><title>Wird geladen<\/title><path d=\"M16 6h-6l2.243-2.243c-1.133-1.133-2.64-1.757-4.243-1.757s-3.109 0.624-4.243 1.757c-1.133 1.133-1.757 2.64-1.757 4.243s0.624 3.109 1.757 4.243c1.133 1.133 2.64 1.757 4.243 1.757s3.109-0.624 4.243-1.757c0.095-0.095 0.185-0.192 0.273-0.292l1.505 1.317c-1.466 1.674-3.62 2.732-6.020 2.732-4.418 0-8-3.582-8-8s3.582-8 8-8c2.209 0 4.209 0.896 5.656 2.344l2.343-2.344v6z\"><\/path>\n\t\t\t\t<\/svg><\/span><span class=\"kadence-svg-iconset svg-baseline\"><svg class=\"kadence-svg-icon kadence-check-svg\" fill=\"currentColor\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewbox=\"0 0 16 16\"><title>Erledigt<\/title><path d=\"M14 2.5l-8.5 8.5-3.5-3.5-1.5 1.5 5 5 10-10z\"><\/path>\n\t\t\t\t<\/svg><\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_22547\" class=\"screen-reader-text\">\n\t\tDieses Produkt weist mehrere Varianten auf. Die Optionen k\u00f6nnen auf der Produktseite gew\u00e4hlt werden\t<\/span>\n<div class=\"xoo-wl-btn-container xoo-wl-btc-variable xoo-wl-btc-popup\"><button type=\"button\" data-product_id=\"22547\" class=\"xoo-wl-action-btn xoo-wl-open-form-btn button btn xoo-wl-btn-popup\" >Ist sie nicht mehr verf&uuml;gbar?&lt;br&gt;Auf die Warteliste setzen<\/button><\/div><\/div><\/div><\/li>\n<li class=\"entry content-bg loop-entry product type-product post-16951 status-publish instock product_cat-olio-extravergine-di-oliva product_tag-fruttato-intenso product_tag-olio-extravergine-di-oliva product_tag-olio-in-bottiglia has-post-thumbnail sale featured shipping-taxable purchasable product-type-variable\">\n\t<a href=\"https:\/\/www.oliosanfilippo.com\/de\/abbonamento\/olio-extravergine-di-oliva-fruttato-intenso\/\" class=\"woocommerce-loop-image-link woocommerce-LoopProduct-link woocommerce-loop-product__link product-has-hover-image\">\n\t<span class=\"onsale\" data-no-translation=\"\" data-trp-gettext=\"\">Angebot!<\/span>\n\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"1204\" src=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/okintenso-scaled-900x1204.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Olio Extravergine di Oliva Fruttato Intenso - Bottiglia\" srcset=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/okintenso-scaled-900x1204.jpg 900w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/okintenso-scaled-600x803.jpg 600w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/okintenso-224x300.jpg 224w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/okintenso-765x1024.jpg 765w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/okintenso-768x1028.jpg 768w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/okintenso-1148x1536.jpg 1148w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/okintenso-1530x2048.jpg 1530w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/okintenso-scaled.jpg 1913w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"650\" src=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2022\/09\/intenso.jpg\" class=\"secondary-product-image attachment-woocommerce_thumbnail attachment-shop-catalog wp-post-image wp-post-image--secondary\" alt=\"\" title=\"intensiv\" srcset=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2022\/09\/intenso.jpg 500w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2022\/09\/intenso-231x300.jpg 231w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><div class=\"product-details content-bg entry-content-wrap\"><h2 class=\"woocommerce-loop-product__title\"><a href=\"https:\/\/www.oliosanfilippo.com\/de\/abbonamento\/olio-extravergine-di-oliva-fruttato-intenso\/\" class=\"woocommerce-LoopProduct-link-title woocommerce-loop-product__title_ink\">Natives Oliven\u00f6l Extra Intensiv Fruchtig - Flasche<\/a><\/h2>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>9.50<\/bdi><\/span> <span aria-hidden=\"true\"> \u2013 <\/span> <span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>107.00<\/bdi><\/span><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Preisspanne: &euro;9.50 bis &euro;107.00<\/span><\/span>\n<div class=\"product-action-wrap\"><a href=\"https:\/\/www.oliosanfilippo.com\/de\/abbonamento\/olio-extravergine-di-oliva-fruttato-intenso\/\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"16951\" data-product_sku=\"Fruttato Intenso Bottiglia\" aria-label=\"W\u00e4hle Optionen f\u00fcr \u201eOlio Extravergine di Oliva Fruttato Intenso - Bottiglia\u201c\" rel=\"nofollow\" data-no-translation-aria-label=\"\">Ausf\u00fchrung w\u00e4hlen<span class=\"kadence-svg-iconset svg-baseline\"><svg aria-hidden=\"true\" class=\"kadence-svg-icon kadence-arrow-right-alt-svg\" fill=\"currentColor\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"28\" viewbox=\"0 0 27 28\"><title>Fortfahren<\/title><path d=\"M27 13.953c0 0.141-0.063 0.281-0.156 0.375l-6 5.531c-0.156 0.141-0.359 0.172-0.547 0.094-0.172-0.078-0.297-0.25-0.297-0.453v-3.5h-19.5c-0.281 0-0.5-0.219-0.5-0.5v-3c0-0.281 0.219-0.5 0.5-0.5h19.5v-3.5c0-0.203 0.109-0.375 0.297-0.453s0.391-0.047 0.547 0.078l6 5.469c0.094 0.094 0.156 0.219 0.156 0.359v0z\"><\/path>\n\t\t\t\t<\/svg><\/span><span class=\"kadence-svg-iconset svg-baseline\"><svg class=\"kadence-svg-icon kadence-spinner-svg\" fill=\"currentColor\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewbox=\"0 0 16 16\"><title>Wird geladen<\/title><path d=\"M16 6h-6l2.243-2.243c-1.133-1.133-2.64-1.757-4.243-1.757s-3.109 0.624-4.243 1.757c-1.133 1.133-1.757 2.64-1.757 4.243s0.624 3.109 1.757 4.243c1.133 1.133 2.64 1.757 4.243 1.757s3.109-0.624 4.243-1.757c0.095-0.095 0.185-0.192 0.273-0.292l1.505 1.317c-1.466 1.674-3.62 2.732-6.020 2.732-4.418 0-8-3.582-8-8s3.582-8 8-8c2.209 0 4.209 0.896 5.656 2.344l2.343-2.344v6z\"><\/path>\n\t\t\t\t<\/svg><\/span><span class=\"kadence-svg-iconset svg-baseline\"><svg class=\"kadence-svg-icon kadence-check-svg\" fill=\"currentColor\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewbox=\"0 0 16 16\"><title>Erledigt<\/title><path d=\"M14 2.5l-8.5 8.5-3.5-3.5-1.5 1.5 5 5 10-10z\"><\/path>\n\t\t\t\t<\/svg><\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_16951\" class=\"screen-reader-text\">\n\t\tDieses Produkt weist mehrere Varianten auf. Die Optionen k\u00f6nnen auf der Produktseite gew\u00e4hlt werden\t<\/span>\n<div class=\"xoo-wl-btn-container xoo-wl-btc-variable xoo-wl-btc-popup\"><button type=\"button\" data-product_id=\"16951\" class=\"xoo-wl-action-btn xoo-wl-open-form-btn button btn xoo-wl-btn-popup\" >Ist sie nicht mehr verf&uuml;gbar?&lt;br&gt;Auf die Warteliste setzen<\/button><\/div><\/div><\/div><\/li>\n<li class=\"entry content-bg loop-entry product type-product post-16649 status-publish last instock product_cat-olio-extravergine-di-oliva product_tag-fruttato-delicato product_tag-fruttato-medio product_tag-olio-extravergine-di-oliva product_tag-olio-in-bottiglia has-post-thumbnail sale shipping-taxable purchasable product-type-variable\">\n\t<a href=\"https:\/\/www.oliosanfilippo.com\/de\/abbonamento\/olio-extravergine-di-oliva-fruttato-delicato-bottiglia\/\" class=\"woocommerce-loop-image-link woocommerce-LoopProduct-link woocommerce-loop-product__link product-has-hover-image\">\n\t<span class=\"onsale\" data-no-translation=\"\" data-trp-gettext=\"\">Angebot!<\/span>\n\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"1204\" src=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/delicato-scaled-900x1204.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Olio Extravergine di Oliva Fruttato Delicato - Bottiglia\" srcset=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/delicato-scaled-900x1204.jpg 900w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/delicato-scaled-600x803.jpg 600w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/delicato-224x300.jpg 224w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/delicato-765x1024.jpg 765w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/delicato-768x1028.jpg 768w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/delicato-1148x1536.jpg 1148w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/delicato-1530x2048.jpg 1530w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/delicato-scaled.jpg 1913w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"550\" src=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2022\/09\/legleg.jpg\" class=\"secondary-product-image attachment-woocommerce_thumbnail attachment-shop-catalog wp-post-image wp-post-image--secondary\" alt=\"\" title=\"legleg\" srcset=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2022\/09\/legleg.jpg 500w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2022\/09\/legleg-273x300.jpg 273w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><div class=\"product-details content-bg entry-content-wrap\"><h2 class=\"woocommerce-loop-product__title\"><a href=\"https:\/\/www.oliosanfilippo.com\/de\/abbonamento\/olio-extravergine-di-oliva-fruttato-delicato-bottiglia\/\" class=\"woocommerce-LoopProduct-link-title woocommerce-loop-product__title_ink\">Natives Oliven\u00f6l Extra Zartfruchtig - Flasche<\/a><\/h2>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>8.00<\/bdi><\/span> <span aria-hidden=\"true\"> \u2013 <\/span> <span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>88.00<\/bdi><\/span><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Preisspanne: &euro;8.00 bis &euro;88.00<\/span><\/span>\n<div class=\"product-action-wrap\"><a href=\"https:\/\/www.oliosanfilippo.com\/de\/abbonamento\/olio-extravergine-di-oliva-fruttato-delicato-bottiglia\/\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"16649\" data-product_sku=\"Fruttato Delicato Bottiglia\" aria-label=\"W\u00e4hle Optionen f\u00fcr \u201eOlio Extravergine di Oliva Fruttato Delicato - Bottiglia\u201c\" rel=\"nofollow\" data-no-translation-aria-label=\"\">Ausf\u00fchrung w\u00e4hlen<span class=\"kadence-svg-iconset svg-baseline\"><svg aria-hidden=\"true\" class=\"kadence-svg-icon kadence-arrow-right-alt-svg\" fill=\"currentColor\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"28\" viewbox=\"0 0 27 28\"><title>Fortfahren<\/title><path d=\"M27 13.953c0 0.141-0.063 0.281-0.156 0.375l-6 5.531c-0.156 0.141-0.359 0.172-0.547 0.094-0.172-0.078-0.297-0.25-0.297-0.453v-3.5h-19.5c-0.281 0-0.5-0.219-0.5-0.5v-3c0-0.281 0.219-0.5 0.5-0.5h19.5v-3.5c0-0.203 0.109-0.375 0.297-0.453s0.391-0.047 0.547 0.078l6 5.469c0.094 0.094 0.156 0.219 0.156 0.359v0z\"><\/path>\n\t\t\t\t<\/svg><\/span><span class=\"kadence-svg-iconset svg-baseline\"><svg class=\"kadence-svg-icon kadence-spinner-svg\" fill=\"currentColor\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewbox=\"0 0 16 16\"><title>Wird geladen<\/title><path d=\"M16 6h-6l2.243-2.243c-1.133-1.133-2.64-1.757-4.243-1.757s-3.109 0.624-4.243 1.757c-1.133 1.133-1.757 2.64-1.757 4.243s0.624 3.109 1.757 4.243c1.133 1.133 2.64 1.757 4.243 1.757s3.109-0.624 4.243-1.757c0.095-0.095 0.185-0.192 0.273-0.292l1.505 1.317c-1.466 1.674-3.62 2.732-6.020 2.732-4.418 0-8-3.582-8-8s3.582-8 8-8c2.209 0 4.209 0.896 5.656 2.344l2.343-2.344v6z\"><\/path>\n\t\t\t\t<\/svg><\/span><span class=\"kadence-svg-iconset svg-baseline\"><svg class=\"kadence-svg-icon kadence-check-svg\" fill=\"currentColor\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewbox=\"0 0 16 16\"><title>Erledigt<\/title><path d=\"M14 2.5l-8.5 8.5-3.5-3.5-1.5 1.5 5 5 10-10z\"><\/path>\n\t\t\t\t<\/svg><\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_16649\" class=\"screen-reader-text\">\n\t\tDieses Produkt weist mehrere Varianten auf. Die Optionen k\u00f6nnen auf der Produktseite gew\u00e4hlt werden\t<\/span>\n<div class=\"xoo-wl-btn-container xoo-wl-btc-variable xoo-wl-btc-popup\"><button type=\"button\" data-product_id=\"16649\" class=\"xoo-wl-action-btn xoo-wl-open-form-btn button btn xoo-wl-btn-popup\" >Ist sie nicht mehr verf&uuml;gbar?&lt;br&gt;Auf die Warteliste setzen<\/button><\/div><\/div><\/div><\/li>\n<\/ul>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-a3ac03d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a3ac03d\" data-element_type=\"section\" data-e-type=\"section\" id=\"offerte\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-72c81e5\" data-id=\"72c81e5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8056c0a elementor-widget elementor-widget-heading\" data-id=\"8056c0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unsere Premium-\u00d6le in Bag in Box oder Tan<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca50ee7 elementor-grid-3 elementor-grid-mobile-1 elementor-grid-tablet-3 elementor-products-grid elementor-wc-products elementor-widget elementor-widget-woocommerce-products\" data-id=\"ca50ee7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"woocommerce-products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"woocommerce columns-3\"><ul class=\"products elementor-grid content-wrap product-archive grid-cols grid-sm-col-2 grid-lg-col-3 woo-archive-action-visible woo-archive-btn-text align-buttons-bottom  woo-archive-image-hover-zoom\"><li class=\"entry content-bg loop-entry product type-product post-22527 status-publish first instock product_cat-olio-extravergine-di-oliva product_tag-biologico product_tag-fruttato-delicato product_tag-olio-extravergine-di-oliva product_tag-olio-in-tanica has-post-thumbnail sale featured shipping-taxable purchasable product-type-variable\">\n\t<a href=\"https:\/\/www.oliosanfilippo.com\/de\/abbonamento\/olio-extravergine-di-oliva-biologico-tanica\/\" class=\"woocommerce-loop-image-link woocommerce-LoopProduct-link woocommerce-loop-product__link product-has-hover-image\">\n\t<span class=\"onsale\" data-no-translation=\"\" data-trp-gettext=\"\">Angebot!<\/span>\n\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"1204\" src=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/tanica-bio-5-l-900x1204.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Olio Extravergine di Oliva Biologico -Tanica\" srcset=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/tanica-bio-5-l-900x1204.jpg 900w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/tanica-bio-5-l-224x300.jpg 224w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/tanica-bio-5-l-765x1024.jpg 765w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/tanica-bio-5-l-768x1028.jpg 768w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/tanica-bio-5-l-1148x1536.jpg 1148w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/tanica-bio-5-l-1530x2048.jpg 1530w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/tanica-bio-5-l-9x12.jpg 9w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/tanica-bio-5-l-600x803.jpg 600w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/tanica-bio-5-l.jpg 1913w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/Untitled-900x900.jpg\" class=\"secondary-product-image attachment-woocommerce_thumbnail attachment-shop-catalog wp-post-image wp-post-image--secondary\" alt=\"olio extravergine di oliva biologico\" title=\"Natives Bio-Oliven\u00f6l extra\" srcset=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/Untitled-900x900.jpg 900w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/Untitled-100x100.jpg 100w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/Untitled-600x600.jpg 600w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/Untitled-300x300.jpg 300w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/Untitled-1024x1024.jpg 1024w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/Untitled-150x150.jpg 150w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/Untitled-768x768.jpg 768w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/Untitled-500x500.jpg 500w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2020\/04\/Untitled.jpg 1500w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><div class=\"product-details content-bg entry-content-wrap\"><h2 class=\"woocommerce-loop-product__title\"><a href=\"https:\/\/www.oliosanfilippo.com\/de\/abbonamento\/olio-extravergine-di-oliva-biologico-tanica\/\" class=\"woocommerce-LoopProduct-link-title woocommerce-loop-product__title_ink\">Natives Bio-Oliven\u00f6l Extra - Tank<\/a><\/h2>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>56.00<\/bdi><\/span> <span aria-hidden=\"true\"> \u2013 <\/span> <span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>312.00<\/bdi><\/span><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Preisspanne: &euro;56.00 bis &euro;312.00<\/span><\/span>\n<div class=\"product-action-wrap\"><a href=\"https:\/\/www.oliosanfilippo.com\/de\/abbonamento\/olio-extravergine-di-oliva-biologico-tanica\/\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"22527\" data-product_sku=\"BIOLOGICO\" aria-label=\"W\u00e4hle Optionen f\u00fcr \u201eOlio Extravergine di Oliva Biologico -Tanica\u201c\" rel=\"nofollow\" data-no-translation-aria-label=\"\">Ausf\u00fchrung w\u00e4hlen<span class=\"kadence-svg-iconset svg-baseline\"><svg aria-hidden=\"true\" class=\"kadence-svg-icon kadence-arrow-right-alt-svg\" fill=\"currentColor\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"28\" viewbox=\"0 0 27 28\"><title>Fortfahren<\/title><path d=\"M27 13.953c0 0.141-0.063 0.281-0.156 0.375l-6 5.531c-0.156 0.141-0.359 0.172-0.547 0.094-0.172-0.078-0.297-0.25-0.297-0.453v-3.5h-19.5c-0.281 0-0.5-0.219-0.5-0.5v-3c0-0.281 0.219-0.5 0.5-0.5h19.5v-3.5c0-0.203 0.109-0.375 0.297-0.453s0.391-0.047 0.547 0.078l6 5.469c0.094 0.094 0.156 0.219 0.156 0.359v0z\"><\/path>\n\t\t\t\t<\/svg><\/span><span class=\"kadence-svg-iconset svg-baseline\"><svg class=\"kadence-svg-icon kadence-spinner-svg\" fill=\"currentColor\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewbox=\"0 0 16 16\"><title>Wird geladen<\/title><path d=\"M16 6h-6l2.243-2.243c-1.133-1.133-2.64-1.757-4.243-1.757s-3.109 0.624-4.243 1.757c-1.133 1.133-1.757 2.64-1.757 4.243s0.624 3.109 1.757 4.243c1.133 1.133 2.64 1.757 4.243 1.757s3.109-0.624 4.243-1.757c0.095-0.095 0.185-0.192 0.273-0.292l1.505 1.317c-1.466 1.674-3.62 2.732-6.020 2.732-4.418 0-8-3.582-8-8s3.582-8 8-8c2.209 0 4.209 0.896 5.656 2.344l2.343-2.344v6z\"><\/path>\n\t\t\t\t<\/svg><\/span><span class=\"kadence-svg-iconset svg-baseline\"><svg class=\"kadence-svg-icon kadence-check-svg\" fill=\"currentColor\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewbox=\"0 0 16 16\"><title>Erledigt<\/title><path d=\"M14 2.5l-8.5 8.5-3.5-3.5-1.5 1.5 5 5 10-10z\"><\/path>\n\t\t\t\t<\/svg><\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_22527\" class=\"screen-reader-text\">\n\t\tDieses Produkt weist mehrere Varianten auf. Die Optionen k\u00f6nnen auf der Produktseite gew\u00e4hlt werden\t<\/span>\n<div class=\"xoo-wl-btn-container xoo-wl-btc-variable xoo-wl-btc-popup\"><button type=\"button\" data-product_id=\"22527\" class=\"xoo-wl-action-btn xoo-wl-open-form-btn button btn xoo-wl-btn-popup\" >Ist sie nicht mehr verf&uuml;gbar?&lt;br&gt;Auf die Warteliste setzen<\/button><\/div><\/div><\/div><\/li>\n<li class=\"entry content-bg loop-entry product type-product post-20205 status-publish instock product_cat-olio-extravergine-di-oliva product_tag-fruttato-intenso product_tag-olio-extravergine-di-oliva product_tag-olio-in-tanica has-post-thumbnail sale featured shipping-taxable purchasable product-type-variable\">\n\t<a href=\"https:\/\/www.oliosanfilippo.com\/de\/abbonamento\/olio-extravergine-di-oliva-fruttato-intenso-bag-in-box\/\" class=\"woocommerce-loop-image-link woocommerce-LoopProduct-link woocommerce-loop-product__link product-has-hover-image\">\n\t<span class=\"onsale\" data-no-translation=\"\" data-trp-gettext=\"\">Angebot!<\/span>\n\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"1204\" src=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Bag-in-Box-Intensa--900x1204.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Olio extravergine di oliva fruttato intenso\" srcset=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Bag-in-Box-Intensa--900x1204.jpg 900w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Bag-in-Box-Intensa--224x300.jpg 224w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Bag-in-Box-Intensa--765x1024.jpg 765w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Bag-in-Box-Intensa--768x1028.jpg 768w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Bag-in-Box-Intensa--1148x1536.jpg 1148w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Bag-in-Box-Intensa--1530x2048.jpg 1530w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Bag-in-Box-Intensa--9x12.jpg 9w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Bag-in-Box-Intensa--600x803.jpg 600w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Bag-in-Box-Intensa-.jpg 1913w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"1204\" src=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Fronte-box-Int--900x1204.jpg\" class=\"secondary-product-image attachment-woocommerce_thumbnail attachment-shop-catalog wp-post-image wp-post-image--secondary\" alt=\"\" title=\"Int box front\" srcset=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Fronte-box-Int--900x1204.jpg 900w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Fronte-box-Int--224x300.jpg 224w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Fronte-box-Int--765x1024.jpg 765w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Fronte-box-Int--768x1028.jpg 768w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Fronte-box-Int--1148x1536.jpg 1148w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Fronte-box-Int--1530x2048.jpg 1530w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Fronte-box-Int--9x12.jpg 9w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Fronte-box-Int--600x803.jpg 600w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Fronte-box-Int-.jpg 1913w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><div class=\"product-details content-bg entry-content-wrap\"><h2 class=\"woocommerce-loop-product__title\"><a href=\"https:\/\/www.oliosanfilippo.com\/de\/abbonamento\/olio-extravergine-di-oliva-fruttato-intenso-bag-in-box\/\" class=\"woocommerce-LoopProduct-link-title woocommerce-loop-product__title_ink\">Natives Oliven\u00f6l Extra Intensiv Fruchtig Beutel In Box<\/a><\/h2>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>54.00<\/bdi><\/span> <span aria-hidden=\"true\"> \u2013 <\/span> <span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>299.00<\/bdi><\/span><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Preisspanne: &euro;54.00 bis &euro;299.00<\/span><\/span>\n<div class=\"product-action-wrap\"><a href=\"https:\/\/www.oliosanfilippo.com\/de\/abbonamento\/olio-extravergine-di-oliva-fruttato-intenso-bag-in-box\/\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"20205\" data-product_sku=\"Fruttato Intenso Bag in Box 5L\" aria-label=\"W\u00e4hle Optionen f\u00fcr \u201eOlio Extravergine di Oliva Fruttato Intenso Bag In Box\u201c\" rel=\"nofollow\" data-no-translation-aria-label=\"\">Ausf\u00fchrung w\u00e4hlen<span class=\"kadence-svg-iconset svg-baseline\"><svg aria-hidden=\"true\" class=\"kadence-svg-icon kadence-arrow-right-alt-svg\" fill=\"currentColor\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"28\" viewbox=\"0 0 27 28\"><title>Fortfahren<\/title><path d=\"M27 13.953c0 0.141-0.063 0.281-0.156 0.375l-6 5.531c-0.156 0.141-0.359 0.172-0.547 0.094-0.172-0.078-0.297-0.25-0.297-0.453v-3.5h-19.5c-0.281 0-0.5-0.219-0.5-0.5v-3c0-0.281 0.219-0.5 0.5-0.5h19.5v-3.5c0-0.203 0.109-0.375 0.297-0.453s0.391-0.047 0.547 0.078l6 5.469c0.094 0.094 0.156 0.219 0.156 0.359v0z\"><\/path>\n\t\t\t\t<\/svg><\/span><span class=\"kadence-svg-iconset svg-baseline\"><svg class=\"kadence-svg-icon kadence-spinner-svg\" fill=\"currentColor\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewbox=\"0 0 16 16\"><title>Wird geladen<\/title><path d=\"M16 6h-6l2.243-2.243c-1.133-1.133-2.64-1.757-4.243-1.757s-3.109 0.624-4.243 1.757c-1.133 1.133-1.757 2.64-1.757 4.243s0.624 3.109 1.757 4.243c1.133 1.133 2.64 1.757 4.243 1.757s3.109-0.624 4.243-1.757c0.095-0.095 0.185-0.192 0.273-0.292l1.505 1.317c-1.466 1.674-3.62 2.732-6.020 2.732-4.418 0-8-3.582-8-8s3.582-8 8-8c2.209 0 4.209 0.896 5.656 2.344l2.343-2.344v6z\"><\/path>\n\t\t\t\t<\/svg><\/span><span class=\"kadence-svg-iconset svg-baseline\"><svg class=\"kadence-svg-icon kadence-check-svg\" fill=\"currentColor\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewbox=\"0 0 16 16\"><title>Erledigt<\/title><path d=\"M14 2.5l-8.5 8.5-3.5-3.5-1.5 1.5 5 5 10-10z\"><\/path>\n\t\t\t\t<\/svg><\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_20205\" class=\"screen-reader-text\">\n\t\tDieses Produkt weist mehrere Varianten auf. Die Optionen k\u00f6nnen auf der Produktseite gew\u00e4hlt werden\t<\/span>\n<div class=\"xoo-wl-btn-container xoo-wl-btc-variable xoo-wl-btc-popup\"><button type=\"button\" data-product_id=\"20205\" class=\"xoo-wl-action-btn xoo-wl-open-form-btn button btn xoo-wl-btn-popup\" >Ist sie nicht mehr verf&uuml;gbar?&lt;br&gt;Auf die Warteliste setzen<\/button><\/div><\/div><\/div><\/li>\n<li class=\"entry content-bg loop-entry product type-product post-20216 status-publish last instock product_cat-olio-extravergine-di-oliva product_tag-fruttato-delicato product_tag-fruttato-medio product_tag-olio-extravergine-di-oliva product_tag-olio-in-tanica has-post-thumbnail sale shipping-taxable purchasable product-type-variable\">\n\t<a href=\"https:\/\/www.oliosanfilippo.com\/de\/abbonamento\/olio-extravergine-di-oliva-fruttato-delicato\/\" class=\"woocommerce-loop-image-link woocommerce-LoopProduct-link woocommerce-loop-product__link product-has-hover-image\">\n\t<span class=\"onsale\" data-no-translation=\"\" data-trp-gettext=\"\">Angebot!<\/span>\n\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"1204\" src=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Bag-in-Box-Delicata--900x1204.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Olio Extravergine di Oliva Fruttato Delicato Bag in Box\" srcset=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Bag-in-Box-Delicata--900x1204.jpg 900w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Bag-in-Box-Delicata--224x300.jpg 224w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Bag-in-Box-Delicata--765x1024.jpg 765w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Bag-in-Box-Delicata--768x1028.jpg 768w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Bag-in-Box-Delicata--1148x1536.jpg 1148w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Bag-in-Box-Delicata--1530x2048.jpg 1530w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Bag-in-Box-Delicata--9x12.jpg 9w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Bag-in-Box-Delicata--600x803.jpg 600w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Bag-in-Box-Delicata-.jpg 1913w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"1204\" src=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Fronte-box-Del-900x1204.jpg\" class=\"secondary-product-image attachment-woocommerce_thumbnail attachment-shop-catalog wp-post-image wp-post-image--secondary\" alt=\"\" title=\"Frontbox Del\" srcset=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Fronte-box-Del-900x1204.jpg 900w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Fronte-box-Del-224x300.jpg 224w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Fronte-box-Del-765x1024.jpg 765w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Fronte-box-Del-768x1028.jpg 768w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Fronte-box-Del-1148x1536.jpg 1148w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Fronte-box-Del-1530x2048.jpg 1530w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Fronte-box-Del-9x12.jpg 9w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Fronte-box-Del-600x803.jpg 600w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/Fronte-box-Del.jpg 1913w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><div class=\"product-details content-bg entry-content-wrap\"><h2 class=\"woocommerce-loop-product__title\"><a href=\"https:\/\/www.oliosanfilippo.com\/de\/abbonamento\/olio-extravergine-di-oliva-fruttato-delicato\/\" class=\"woocommerce-LoopProduct-link-title woocommerce-loop-product__title_ink\">Natives Oliven\u00f6l Extra Zartfruchtig Bag in Box<\/a><\/h2>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>51.50<\/bdi><\/span> <span aria-hidden=\"true\"> \u2013 <\/span> <span class=\"woocommerce-Price-amount amount\" aria-hidden=\"true\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>290.00<\/bdi><\/span><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">Preisspanne: &euro;51.50 bis &euro;290.00<\/span><\/span>\n<div class=\"product-action-wrap\"><a href=\"https:\/\/www.oliosanfilippo.com\/de\/abbonamento\/olio-extravergine-di-oliva-fruttato-delicato\/\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"20216\" data-product_sku=\"Fruttato Delicato Bag in Box\" aria-label=\"W\u00e4hle Optionen f\u00fcr \u201eOlio Extravergine di Oliva Fruttato Delicato Bag in Box\u201c\" rel=\"nofollow\" data-no-translation-aria-label=\"\">Ausf\u00fchrung w\u00e4hlen<span class=\"kadence-svg-iconset svg-baseline\"><svg aria-hidden=\"true\" class=\"kadence-svg-icon kadence-arrow-right-alt-svg\" fill=\"currentColor\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"28\" viewbox=\"0 0 27 28\"><title>Fortfahren<\/title><path d=\"M27 13.953c0 0.141-0.063 0.281-0.156 0.375l-6 5.531c-0.156 0.141-0.359 0.172-0.547 0.094-0.172-0.078-0.297-0.25-0.297-0.453v-3.5h-19.5c-0.281 0-0.5-0.219-0.5-0.5v-3c0-0.281 0.219-0.5 0.5-0.5h19.5v-3.5c0-0.203 0.109-0.375 0.297-0.453s0.391-0.047 0.547 0.078l6 5.469c0.094 0.094 0.156 0.219 0.156 0.359v0z\"><\/path>\n\t\t\t\t<\/svg><\/span><span class=\"kadence-svg-iconset svg-baseline\"><svg class=\"kadence-svg-icon kadence-spinner-svg\" fill=\"currentColor\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewbox=\"0 0 16 16\"><title>Wird geladen<\/title><path d=\"M16 6h-6l2.243-2.243c-1.133-1.133-2.64-1.757-4.243-1.757s-3.109 0.624-4.243 1.757c-1.133 1.133-1.757 2.64-1.757 4.243s0.624 3.109 1.757 4.243c1.133 1.133 2.64 1.757 4.243 1.757s3.109-0.624 4.243-1.757c0.095-0.095 0.185-0.192 0.273-0.292l1.505 1.317c-1.466 1.674-3.62 2.732-6.020 2.732-4.418 0-8-3.582-8-8s3.582-8 8-8c2.209 0 4.209 0.896 5.656 2.344l2.343-2.344v6z\"><\/path>\n\t\t\t\t<\/svg><\/span><span class=\"kadence-svg-iconset svg-baseline\"><svg class=\"kadence-svg-icon kadence-check-svg\" fill=\"currentColor\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewbox=\"0 0 16 16\"><title>Erledigt<\/title><path d=\"M14 2.5l-8.5 8.5-3.5-3.5-1.5 1.5 5 5 10-10z\"><\/path>\n\t\t\t\t<\/svg><\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_20216\" class=\"screen-reader-text\">\n\t\tDieses Produkt weist mehrere Varianten auf. Die Optionen k\u00f6nnen auf der Produktseite gew\u00e4hlt werden\t<\/span>\n<div class=\"xoo-wl-btn-container xoo-wl-btc-variable xoo-wl-btc-popup\"><button type=\"button\" data-product_id=\"20216\" class=\"xoo-wl-action-btn xoo-wl-open-form-btn button btn xoo-wl-btn-popup\" >Ist sie nicht mehr verf&uuml;gbar?&lt;br&gt;Auf die Warteliste setzen<\/button><\/div><\/div><\/div><\/li>\n<\/ul>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Die Produkte unserer jahrhundertealten Traditionen Entdecken Sie unser unglaubliches Natives Oliven\u00f6l Extra, das nur aus italienischen Bergoliven hergestellt wird 100% Unsere feinen \u00d6le in Flaschen Unsere feinen \u00d6le in Bag in Box oder Tanica<\/p>","protected":false},"author":26,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_surecart_dashboard_logo_width":"180px","_surecart_dashboard_show_logo":true,"_surecart_dashboard_navigation_orders":true,"_surecart_dashboard_navigation_invoices":true,"_surecart_dashboard_navigation_subscriptions":true,"_surecart_dashboard_navigation_downloads":true,"_surecart_dashboard_navigation_billing":true,"_surecart_dashboard_navigation_account":true,"inline_featured_image":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-20412","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.oliosanfilippo.com\/de\/wp-json\/wp\/v2\/pages\/20412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oliosanfilippo.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.oliosanfilippo.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.oliosanfilippo.com\/de\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oliosanfilippo.com\/de\/wp-json\/wp\/v2\/comments?post=20412"}],"version-history":[{"count":62,"href":"https:\/\/www.oliosanfilippo.com\/de\/wp-json\/wp\/v2\/pages\/20412\/revisions"}],"predecessor-version":[{"id":23007,"href":"https:\/\/www.oliosanfilippo.com\/de\/wp-json\/wp\/v2\/pages\/20412\/revisions\/23007"}],"wp:attachment":[{"href":"https:\/\/www.oliosanfilippo.com\/de\/wp-json\/wp\/v2\/media?parent=20412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}