{"id":22994,"date":"2024-10-30T22:46:37","date_gmt":"2024-10-30T21:46:37","guid":{"rendered":"https:\/\/www.oliosanfilippo.com\/?post_type=product&#038;p=22994"},"modified":"2025-10-11T12:56:23","modified_gmt":"2025-10-11T10:56:23","slug":"olio-extravergine-di-oliva-novello","status":"publish","type":"product","link":"https:\/\/www.oliosanfilippo.com\/de\/abbonamento\/olio-extravergine-di-oliva-novello\/","title":{"rendered":"Alik\u00f2s Olio EVO Novello Fresco di Frantoio 2025"},"content":{"rendered":"\t\t<div data-elementor-type=\"product-post\" data-elementor-id=\"22994\" class=\"elementor elementor-22994\" data-elementor-post-type=\"product\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-4153ab5c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4153ab5c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-239e7eec\" data-id=\"239e7eec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ed72433 elementor-widget elementor-widget-text-editor\" data-id=\"3ed72433\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong style=\"color: var(--global-palette3); font-family: var(--global-heading-font-family); background-color: transparent;\">Alik\u00f2s Olio Extravergine di oliva NOVELLO Fresco di Frantoio<\/strong><\/h2><p>Il nostro Olio Extravergine Novello \u00e8 il primo olio extravergine dell&#8217;annata, il primo estratto dalle olive raccolte e molite esclusivamente nella prima settimana di produzione (dal 14 al 21 di ottobre). Si tratta di un olio il cui sapore caratteristico \u00e8 largamente apprezzato, tanto che nel nostro territorio si organizzano addirittura feste in suo onore.<\/p><p>L&#8217;<strong>Olio extravergine di oliva Novello Alik\u00f2s<\/strong> \u00e8 prodotto nel nostro Frantoio utilizzando cultivar di olive provenienti dal territorio dei Monti Sicani\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p><p><span style=\"background-color: transparent; color: var(--global-palette4); font-family: var(--global-body-font-family);\">Presenta note sensoriali uniche che richiamano l&#8217;aroma dell&#8217;<b>erba<\/b>, della <b>mandorla fresca<\/b>, del <b>carciofo<\/b> e\u00a0<\/span><span style=\"background-color: transparent; color: var(--global-palette4); font-family: var(--global-body-font-family);\">qualche nota delicata di <b>pomodoro<\/b> appena raccolto,<\/span><span style=\"background-color: transparent; color: var(--global-palette4); font-family: var(--global-body-font-family);\">\u00a0rendendolo cos\u00ec un olio amabile dal <b>flavor delicato <\/b>e dal gusto particolarmente <b>intenso<\/b>.\u00a0<\/span><\/p><p>Questi suggestioni gustative rispecchiano le caratteristiche del territorio di raccolta degli ulivi che producono particolari variet\u00e0 di olive di montagna che vengono raccolte nei <b>monti Sicani <\/b>al centro della Sicilia, un contesto agricolo tradizionale con una cultura frantoiana millenaria.<\/p><p><span style=\"background-color: transparent; color: var(--global-palette4); font-family: var(--global-body-font-family);\">Le olive vengono raccolte a mano ancora verdissime e trasportate al frantoio <\/span><b style=\"background-color: transparent; color: var(--global-palette4); font-family: var(--global-body-font-family);\">entro 48 ore<\/b><span style=\"background-color: transparent; color: var(--global-palette4); font-family: var(--global-body-font-family);\"> per essere sottoposte al processo di estrazione a freddo. Questo metodo di produzione consente di conservare tutte le caratteristiche organolettiche delle olive, garantendo un olio extravergine di oliva dal gusto e sapore intenso che richiama i sapori della terra siciliana.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06d6213 elementor-widget elementor-widget-heading\" data-id=\"06d6213\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Analisi Sensoriale Olio EVO Alik\u00f2s<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c2f497 elementor-widget elementor-widget-image\" data-id=\"8c2f497\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1036\" height=\"838\" src=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2022\/10\/Screenshot-2024-10-17-alle-17.10.22.png\" class=\"attachment-full size-full wp-image-22935\" alt=\"\" srcset=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2022\/10\/Screenshot-2024-10-17-alle-17.10.22.png 1036w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2022\/10\/Screenshot-2024-10-17-alle-17.10.22-300x243.png 300w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2022\/10\/Screenshot-2024-10-17-alle-17.10.22-1024x828.png 1024w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2022\/10\/Screenshot-2024-10-17-alle-17.10.22-768x621.png 768w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2022\/10\/Screenshot-2024-10-17-alle-17.10.22-15x12.png 15w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2022\/10\/Screenshot-2024-10-17-alle-17.10.22-900x728.png 900w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2022\/10\/Screenshot-2024-10-17-alle-17.10.22-600x485.png 600w\" sizes=\"(max-width: 1036px) 100vw, 1036px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66cfa7d4 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-premium-chart\" data-id=\"66cfa7d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;type&quot;:&quot;radar&quot;,&quot;x_axis_label_switch&quot;:&quot;true&quot;,&quot;x_axis_label&quot;:&quot;X-Axis&quot;,&quot;x_axis_labels&quot;:&quot;Oliva Matura, Oliva Acerba, Noce, Pinolo, Mandorla Secca, Mandorla Fresca, Mela, Pomodoro, Melanzana, Cardo, Carciofo, Erba, Piccante, Amaro - Oliva, Amaro - Legno, Amaro Tannico&quot;,&quot;x_axis_begin&quot;:&quot;true&quot;,&quot;y_axis_label_switch&quot;:&quot;true&quot;,&quot;y_axis_label&quot;:&quot;Y-Axis&quot;,&quot;tool_tips&quot;:&quot;true&quot;,&quot;data_source&quot;:&quot;custom&quot;,&quot;x_axis_grid&quot;:&quot;true&quot;,&quot;x_axis_label_rotation&quot;:0,&quot;data_type&quot;:&quot;linear&quot;,&quot;y_axis_grid&quot;:&quot;true&quot;,&quot;y_axis_begin&quot;:&quot;true&quot;,&quot;y_axis_urls_target&quot;:&quot;true&quot;,&quot;y_axis_max&quot;:1,&quot;tool_tips_mode&quot;:&quot;nearest&quot;,&quot;start_animation&quot;:&quot;easeInQuad&quot;,&quot;render_event&quot;:&quot;scroll&quot;,&quot;x_axis_label_size&quot;:12,&quot;x_axis_labels_size&quot;:12,&quot;x_axis_grid_color&quot;:&quot;#6ec1e4&quot;,&quot;x_axis_grid_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;y_axis_label_size&quot;:12,&quot;y_axis_labels_size&quot;:12,&quot;y_axis_grid_color&quot;:&quot;#54595f&quot;,&quot;y_axis_grid_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]}}\" data-widget_type=\"premium-chart.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t<div id=\"premium-chart-container-66cfa7d4\" class=\"premium-chart-container\" data-chart=\"[{&quot;label&quot;:&quot;Biologico&quot;,&quot;data&quot;:[&quot;1&quot;,&quot; 4&quot;,&quot; 1.5&quot;,&quot; 0.5&quot;,&quot; 1&quot;,&quot; 3&quot;,&quot; 1&quot;,&quot; 2&quot;,&quot; 1&quot;,&quot; 4&quot;,&quot; 4&quot;,&quot; 5&quot;,&quot; 4&quot;,&quot; 2&quot;,&quot; 1&quot;,&quot; 1&quot;],&quot;links&quot;:[&quot;&quot;],&quot;backgroundColor&quot;:[&quot;#6AC88C91&quot;,&quot;#FF4C19&quot;],&quot;borderColor&quot;:&quot;#2CC204&quot;,&quot;borderWidth&quot;:2}]\" data-settings=\"{&quot;chartId&quot;:&quot;premium-chart-canvas-66cfa7d4&quot;,&quot;height&quot;:400}\">\r\n\t\t\t\t\t<div class=\"premium-chart-title-container\"><h5 class=\"premium-chart-title\">Analisi Sensoriale Olio EVO Biologico<\/h5><\/div>\r\n\t\t\t\t<div class=\"premium-chart-canvas-container\">\r\n\t\t\t<canvas id=\"premium-chart-canvas-66cfa7d4\" class=\"premium-chart-canvas\" width=\"400\" height=\"400\"><\/canvas>\r\n\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5cc581e0 elementor-widget elementor-widget-spacer\" data-id=\"5cc581e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-665fc54c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"665fc54c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-571d62f\" data-id=\"571d62f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51c9ec8c elementor-align-center elementor-widget elementor-widget-button\" data-id=\"51c9ec8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"\/shop\/olio-extravergine-di-oliva-biologico-bottiglia\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scegli CONFEZIONE e FORMATO <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50af6b77 elementor-widget elementor-widget-text-editor\" data-id=\"50af6b77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Presenta note sensoriali uniche che richiamano l\u2019aroma dell\u2019<b>erba<\/b>, della&nbsp;<b>mandorla fresca<\/b>, del&nbsp;<b>carciofo<\/b>&nbsp;e&nbsp;qualche nota delicata di&nbsp;<b>pomodoro<\/b>&nbsp;appena raccolto,&nbsp;rendendolo cos\u00ec un olio amabile dal&nbsp;<b>flavor delicato&nbsp;<\/b>e dal gusto particolarmente&nbsp;<b>intenso<\/b>.&nbsp;<strong>Scheda Tecnica<\/strong><\/h2>\n<p><strong>Ingredienti: <\/strong>Olio extravergine d\u2019oliva di qualit\u00e0 superiore<br><strong>Informazioni Nutrizionali (Valori medi riferiti a 100ml):<\/strong>Valore energetico 821 Kcal \/ 3374 Kj; Grassi 94g, di cui Saturi 14g; Carboidrati 0g, di cui Zuccheri 0g; Proteine 0g; Sale 0g.<br><strong>Altitudine: <\/strong>500\/800 MT S.L.M.<br><strong>Variet\u00e0: <\/strong>Nocellara del Belice, Biancolilla, Carolea, Giarraffa, Cerasuola.<br><strong>Zona di produzione: <\/strong>territorio dei Monti Sicani.<br><strong>Anno produzione:&nbsp;<\/strong>Campagna olearia attuale.<strong><br><\/strong><strong>Periodo di raccolta: <\/strong>Dal 14 ottobre al 21 ottobre<br><strong>Tecnica di Raccolta: <\/strong>Mediante brucatura a mano.<br><strong>Processo di estrazione: <\/strong>A ciclo continuo, a tre fasi, a freddo con temperatura max 25\u00b0.<br><strong>Garanzia:<\/strong>&nbsp;Prodotto 100% italiano da filiera controllata<br><strong>Aspetto: <\/strong>Verde intenso, non filtrato.<br><strong>Conservazione:<\/strong>&nbsp;Silos inox a temperatura controllata<br><strong>Fruttato all\u2019olfatto:<\/strong>&nbsp;Intenso<br><strong>Amaro\/piccante al gusto:<\/strong>&nbsp;Intenso<br><strong>Packaging:<\/strong> Bottiglia di vetro chiara formato 500 ml<br><strong>Data di scadenza:<\/strong>&nbsp;18 mesi dalla data di confezionamento<br><strong>Impiego: <\/strong>Ideale per cucinare e per condire piatti di tutti i giorni.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-4d39a7a9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4d39a7a9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-67947394\" data-id=\"67947394\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c62c35 elementor-widget elementor-widget-image\" data-id=\"3c62c35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/5-1024x683.jpg\" class=\"attachment-large size-large wp-image-22536\" alt=\"\" srcset=\"https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/5-1024x683.jpg 1024w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/5-300x200.jpg 300w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/5-768x512.jpg 768w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/5-900x600.jpg 900w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/5-600x400.jpg 600w, https:\/\/www.oliosanfilippo.com\/wp-content\/uploads\/2023\/11\/5.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-261af3b1\" data-id=\"261af3b1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6db17893 elementor-widget elementor-widget-text-editor\" data-id=\"6db17893\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em><strong>L&#8217;olio Novello \u00e8 a disponibilit\u00e0 limitata<\/strong><\/em><\/p><p>Il nostro olio Novello prodotto annualmente soltanto nella prima settimana di Ottobre, \u00e8 estremamente richiesto e pertanto ha una disponibilit\u00e0 limitata a magazzino.<\/p><p>Se vuoi assaggiarlo, non aspettare troppo in quanto potrebbe non essere pi\u00f9 disponibile in breve tempo.!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d040fc6 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6d040fc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"\/shop\/olio-extravergine-di-oliva-biologico-bottiglia\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scegli CONFEZIONE e FORMATO <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Warum w\u00e4hlen <strong>ALIK\u00f2S<\/strong>\u00a0<strong>l&#8217;olio extravergine di oliva NOVELLO<\/strong>:<br \/>\n\u25fe E&#8217; il primo olio dell&#8217;anno. Le prime gocce della nuova produzione<br \/>\n\u25fe Prodotto da olive coltivate nel territorio dei Monti Sicani<br \/>\n\u25fe Consigliato se non vedi l&#8217;ora di assaporare l&#8217;olio come in frantoio.<br \/>\n\u25fe Campagna olivicola attuale<br \/>\n\u25fe Olio di montagna ad alto contenuto di polifenoli<br \/>\n\u25fe Formato bottiglia 500 ml<\/p>\n<p>&nbsp;<\/p>","protected":false},"featured_media":23028,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_surecart_dashboard_logo_width":"180px","_surecart_dashboard_show_logo":true,"_surecart_dashboard_navigation_orders":true,"_surecart_dashboard_navigation_invoices":true,"_surecart_dashboard_navigation_subscriptions":true,"_surecart_dashboard_navigation_downloads":true,"_surecart_dashboard_navigation_billing":true,"_surecart_dashboard_navigation_account":true,"inline_featured_image":false,"_kad_post_transparent":"default","_kad_post_title":"","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"default","_kad_post_vertical_padding":"default","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"product_brand":[],"product_cat":[40],"product_tag":[58,44,42,60],"class_list":{"0":"post-22994","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-olio-extravergine-di-oliva","7":"product_tag-fruttato-delicato","8":"product_tag-fruttato-medio","9":"product_tag-olio-extravergine-di-oliva","10":"product_tag-olio-in-bottiglia","12":"first","13":"instock","14":"shipping-taxable","15":"purchasable","16":"product-type-simple","17":"entry","18":"content-bg","19":"loop-entry"},"_links":{"self":[{"href":"https:\/\/www.oliosanfilippo.com\/de\/wp-json\/wp\/v2\/product\/22994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oliosanfilippo.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.oliosanfilippo.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oliosanfilippo.com\/de\/wp-json\/wp\/v2\/comments?post=22994"}],"version-history":[{"count":17,"href":"https:\/\/www.oliosanfilippo.com\/de\/wp-json\/wp\/v2\/product\/22994\/revisions"}],"predecessor-version":[{"id":23482,"href":"https:\/\/www.oliosanfilippo.com\/de\/wp-json\/wp\/v2\/product\/22994\/revisions\/23482"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oliosanfilippo.com\/de\/wp-json\/wp\/v2\/media\/23028"}],"wp:attachment":[{"href":"https:\/\/www.oliosanfilippo.com\/de\/wp-json\/wp\/v2\/media?parent=22994"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.oliosanfilippo.com\/de\/wp-json\/wp\/v2\/product_brand?post=22994"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.oliosanfilippo.com\/de\/wp-json\/wp\/v2\/product_cat?post=22994"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.oliosanfilippo.com\/de\/wp-json\/wp\/v2\/product_tag?post=22994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}